{"id":140,"date":"2015-08-03T09:30:56","date_gmt":"2015-08-03T09:30:56","guid":{"rendered":"https:\/\/islabonita.com\/de\/location\/santa-cruz-de-la-palma\/"},"modified":"2016-02-17T12:14:20","modified_gmt":"2016-02-17T12:14:20","slug":"santa-cruz-de-la-palma","status":"publish","type":"location","link":"https:\/\/islabonita.com\/de\/lage\/santa-cruz-de-la-palma\/","title":{"rendered":"Santa Cruz de La Palma"},"content":{"rendered":"<p style=\"text-align: justify;\">Die Gemeinde liegt am \u00f6stlichen Hang der Insel, senkrecht zur Meer-Gipfel-Linie, und umfasst eine Fl\u00e4che von 43,47 Quadratkilometern, was 6,12% der gesamten Inselfl\u00e4che ausmacht. Die Gemeinde grenzt im Norden an die Schlucht Barranco Seco mit der Stadt Puntallana, im S\u00fcden an die Schlucht Barranco de Juan Mayor mit der Stadt Bre\u00f1a Alta, im Osten liegt der Ozean und im Westen der Bergr\u00fccken Cumbre Nueva mit dem Nationalpark La Caldera de Taburiente. Hier befindet sich die gr\u00f6\u00dfte Erh\u00f6hung der Insel (Pico de La Nieve, 2.247 m).<\/p>\n<p style=\"text-align: justify;\">Der gesamte Hang ist von tiefen Schluchten durchzogen, die im Laufe eines langen Erosionsprozesses ohne die Landschaft ver\u00e4ndernde Eruptionen entstanden sind. Der einzige nennenswerte Vulkantrichter ist der Berg Tagoja in 1.097 m H\u00f6he.<\/p>\n<p style=\"text-align: justify;\">Die erste Ansiedlung von Menschen im ehemaligen Bezirk Tedote geht bis in die erste H\u00e4lfte des ersten Jahrtausends vor Christus zur\u00fcck, als die ersten Siedlergruppen aus Nordafrika kamen. An einigen als Wahrzeichen dienenden Orten wie den H\u00f6hlen des Berges Morro de Las Nieves ist ihre Gegenwart sogar durch H\u00f6hlenbilder, Kan\u00e4le, Tiegel und die an den Gipfeln der Gemeinde liegende La Erita belegt (Sammlung von H\u00f6hlenbildern mit \u00fcber 300 Motiven).<\/p>\n<p style=\"text-align: justify;\">Im Jahre 1493 wird die Stadt Santa Cruz de La Palma gegr\u00fcndet und die Eroberung der Insel durch die Spanier findet ihren H\u00f6hepunkt. In kurzer Zeit bestimmt die Stadt die soziopolitische und wirtschaftliche Entwicklung der Insel und eine neue Gesellschaft bildet sich. Es entsteht eine Mischung und Kreuzung aus Ureinwohnern, Spaniern und Europ\u00e4ern, aus der das typische Wesen der Bewohner von La Palma hervorgeht, die ihrer Heimat voller Stolz eine \u00fcberaus starke Liebe entgegenbringen.<\/p>\n<p style=\"text-align: justify;\">Die Geschichte von Santa Cruz de La Palma teilt sich in die Zeit vor und nach dem Jahre 1553: Am 21.Juli wurden ihre Einwohner von einer Invasion von 700 franz\u00f6sische Korsaren \u00fcberrascht, die neun Tage lang die Stadt beherrschten und diese zerst\u00f6rten, bevor sie vertrieben werden konnten. Von hier an bildet sich eine neue st\u00e4dtebauliche Grundlage, die heute von historisch-k\u00fcnstlerischem Interesse ist. Die gewerbliche Grundlage wird 1558 geschaffen, als das erste Spanisch-Amerikanische Gericht entsteht, was eine eindrucksvolle merkantilistische Entwicklung mit sich brachte (der Hafen von Santa Cruz de La Palma war damals der drittgr\u00f6\u00dfte weltweit). Als Folge dieser Handelsaktivit\u00e4ten entwickelte sich in der Stadtder Schiffsbau, der von gro\u00dfer Bedeutung war und zu hohem Ansehen f\u00fchrte. Gleichfalls sehr bedeutend war der Seidenhandel, das weit \u00fcber unsere Inseln hinaus bekannt ist.<\/p>\n<p style=\"text-align: justify;\">Einen wichtigen Punkt in der Geschichte von Santa Cruz de La Palma stellte der Kampf gegen den Machtmissbrauch dar, der von den im Rathaus auf Lebenszeit berufenen Ratsherren ausge\u00fcbt wurde. Als Folge daraus kam es im Januar 1773 zur demokratischen Wahl der politischen Vertreter durch die Bewohner der Gemeinde. Diese Stadt hat als erste im ganzen K\u00f6nigreich Spanien die Demokratie eingef\u00fchrt, noch bevor Nordamerika die Unabh\u00e4ngigkeit erlangte und die erste Verfassung entstand.<\/p>\n<p style=\"text-align: justify;\">Durch das starke Interesse an der Aufkl\u00e4rung verwandelt sich die Stadt in der zweiten H\u00e4lfte des neunzehnten Jahrhunderts zum Zentrum f\u00fcr neue Lehren, Freimaurerlogen, Ver\u00f6ffentlichungen, es entstehen Museen, ein Gemeindekrankenhaus, ein Waisenhaus, neue politische Ideale werden geboren, kulturelle Verb\u00e4nde gegr\u00fcndet, die K\u00fcnste, Musik, Theater, Kino, die industrielle und technologische Entwicklungen wie das elektrische Licht, Telegraphie und Fernsprechwesen erfahren einen Impuls.<\/p>\n<h3 style=\"text-align: justify;\">FESTE<\/h3>\n<h4 style=\"text-align: justify;\">Baile de Los Enanos &#8211; Baja de La Virgen<\/h4>\n<p><a href=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma3-1.jpg\" rel=\"attachment wp-att-1306\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1306 alignleft\" src=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma3-1-300x196.jpg\" alt=\"es_sc_palma_sc_palma3\" width=\"300\" height=\"196\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Die Festtage sind durch die \u00fcber das Jahr verteilten Feiern eng mit der christlichen Tradition verbunden.<\/p>\n<p style=\"text-align: justify;\">Die Kr\u00f6nung ist die alle f\u00fcnf Jahre stattfindende Bajada de La Virgen de Las Nieves, der Abstieg der &#8220;Jungfrau vom Schnee&#8221; von ihrem Heiligtum auf dem Berg bis in die Stadt hinab. Dieses Fest wird seit dem siebzehnten Jahrhundert begangen und gr\u00fcndet sich auf den zahlreichen Wundern, die der Jungfrau von den Einwohnern der Stadt am Ende von Trockenperioden, Fernbleiben von Epidemien oder L\u00f6schen von Feuern und Vulkanen zugesprochen wurden.<\/p>\n<p style=\"text-align: justify;\">Die Bajada wurde 1965 zum Nationalen Fest von touristischer Bedeutung erkl\u00e4rt. \u00dcber einen Monat lang finden, anl\u00e4sslich dessen zahlreiche religi\u00f6se und andere Umz\u00fcge wie der echte Tanz der Zwerge, das Menuett, der Allegorische Wagen, der Dialog zwischen Burg und Schiff, das Festspiel (Loa) u.a. statt.<\/p>\n<p style=\"text-align: justify;\">Am 3. Mai wird die zum \u00f6rtlichen Fest erkl\u00e4rte Kreuzerh\u00f6hung zelebriert. Die verschiedenen Stadtviertel schm\u00fccken ihre Kreuze mit Blumen und Kostbarkeiten. Als Gegensatz dazu ist es Brauch, die Mayos, aus Lumpen gemachte Figuren, auszustellen und damit das Schauspiel zu zieren.<\/p>\n<p style=\"text-align: justify;\">Weihnachten erh\u00e4lt ein ganz besonderes Flair in den von weichen und heiteren Melodien der Gitarrenmusik untermalten N\u00e4chten, die von den durch die Stra\u00dfen der Stadt ziehenden &#8220;Los Divinos&#8221; vorgetragen werden.<\/p>\n<p style=\"text-align: justify;\">Als Letztes ist noch der originelle Tag der Indianer im Fasching zu nennen, dessen Umzug in Wei\u00df sich in eine Wolke von Talkumpuder eingeh\u00fcllt durch die Calle Real bewegt.<\/p>\n<h3 style=\"text-align: justify;\"><strong>ANREGUNGEN<\/strong><\/h3>\n<p style=\"text-align: justify;\">Zwischen Meer und Bergen bieten sich zahlreiche Wege f\u00fcr Wanderungen an. Wir schlagen ihnen zwei Routen vor, und zwar eine kurze, durch die Schlucht Barranco de Las Nieves bis zum Heiligtum der Virgen de Las Nieves f\u00fchrende Strecke oder mehrst\u00fcndige Wanderausfl\u00fcge wie der von der Hauptstadt \u00fcber den Hang bis zur Wallfahrtskapelle Ermita del Pino in El Paso f\u00fchrende Ausflug.<\/p>\n<p style=\"text-align: justify;\">Vom Stadtviertel Calcinas ausgehend kn\u00fcpft sie an die ehemalige Hauptstra\u00dfe La Estrella in Richtung Zisterzienserkloster in Bre\u00f1a Alta. Die bestens ausgeschilderten Wege f\u00fchren uns zum Dorf Botazo und von dort aus kreuzen wir die Schlucht bis zu einem schmalen, gepflasterten Weg, der unter dem dichten Lorbeerwald entlangl\u00e4uft und uns bis zum Gipfel des Berghangs f\u00fchrt, von wo aus wir durch den Pinienwald bis zur Ermita del Pino absteigen.<\/p>\n<p style=\"text-align: justify;\">Eine ebenfalls lange Wanderroute ist der Weg von Meeresspiegelh\u00f6he bis zum Pico de La Nieve oder umgekehrt. Die Wanderung bringt uns durch Mirca, \u00fcber den Berg Tagoja und Fuente Ol\u00e9n auf eine H\u00f6he von 2.235 m und l\u00e4sst uns nacheinander die verschiedenen Vegetationsstufen durchlaufen.<\/p>\n<h3 style=\"text-align: justify;\"><strong>SEHENSW\u00dcRDIGKEITEN<\/strong><\/h3>\n<h4 style=\"text-align: justify;\"><strong>Die Calle Real<\/strong><\/h4>\n<p><a href=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma2-1.jpg\" rel=\"attachment wp-att-1308\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1308 alignleft\" src=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma2-1-300x198.jpg\" alt=\"es_sc_palma_sc_palma2\" width=\"300\" height=\"198\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Vom Hafen bis zu La Alameda (O&#8217;Daly- und P\u00e9rez de Brito-Stra\u00dfe) verl\u00e4uft parallel zur Meeresbrandung die Calle Real. Ihre blanken Pflastersteine erz\u00e4hlen von der ereignisreichen Geschichte dieser Inselhauptstadt. Die Calle Real bildet die Hauptader der Stadt und ist ein beliebter Treffpunkt f\u00fcr deren Bewohner. Im 16. und 17. Jahrhundert haben viele wohlhabende (spanische, portugiesische, fl\u00e4mische, genovesische&#8230;) Familien sie als bevorzugten Ort f\u00fcr den Bau ihrer Herrenh\u00e4user und Pal\u00e4ste gew\u00e4hlt. Ihre Bedeutung als Handelsstadt aus damaliger Zeit hat sie mit einem soziokulturellen Leben durchtr\u00e4nkt, aus dem sich ihr gro\u00dfartiges Verm\u00e4chtnis ergibt.<\/p>\n<p style=\"text-align: justify;\">Die repr\u00e4sentativsten Geb\u00e4ude der zivilen wie auch kirchlichen Macht treffen in dieser Stra\u00dfe mit ihren offenen Vorhallen, auff\u00e4lligen T\u00fcr\u00f6ffnern und gro\u00dfen Fenstern aufeinander.<\/p>\n<p style=\"text-align: justify;\">\n<h4 style=\"text-align: justify;\"><span class=\"titular\"><strong>Die K\u00f6nigsburg Santa Catalina<\/strong><br \/>\n<\/span><\/h4>\n<p style=\"text-align: justify;\">Die Festung Santa Catalina liegt nahe La Alameda am Ende der Avenida. Die dicken Steinmauern umgeben dieses nationalhistorische Denkmal, das Teil des Verteidigungsg\u00fcrtels war, der die Stadt sch\u00fctzte.<\/p>\n<p style=\"text-align: justify;\">Karl V. beauftragte den italienischen Baumeister Leonardo Torriani mit dem Entwurf der Burg (1585), welche die Angriffe der Piraten und Korsaren abwehrte, die das Archipel belagerten.<br \/>\nIn ihren G\u00e4rten steht die auf den Passat anspielende Skulptur des kanarischen K\u00fcnstlers Chirino.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Avenida de los Balcones &#8211; Die Stra\u00dfe der Balkone<\/strong><\/h4>\n<p><a href=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma5.jpg\" rel=\"attachment wp-att-1302\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1302 alignleft\" src=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma5-300x200.jpg\" alt=\"es_sc_palma_sc_palma5\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p align=\"justify\">Santa Cruz de La Palma schmiegt sich an die H\u00e4nge der Landschaft und erlangt so ihr stufenf\u00f6rmiges Stadtbild, gepr\u00e4gt von engen Gassen, die uns mit dem seem\u00e4nnischen Charme eines auf das Meer blickenden Ortes durch die Winkel der Stadt f\u00fchren.<\/p>\n<p align=\"justify\">Neben dem Ozean verl\u00e4uft die alte Stra\u00dfe La Marina; das Wasser bespritzt die Besucher mit Salz, welche die \u00fcbereinandergesetzten Balkone der Avenida fotografieren. Einst an die R\u00fcckfassaden der bedeutenden Herrenh\u00e4user in der Calle Real verbannt, sind sie heute sch\u00f6ne und privilegierte Aussichtsorte, aus Holz geschnitzt, berggr\u00fcn gestrichen und mit unauff\u00e4lligen Jalousien versehen oder verglast.<\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n<p align=\"justify\">\n<h4 align=\"justify\"><span class=\"titular\"><strong>Wahrzeichen<\/strong><\/p>\n<p><\/span><\/h4>\n<p align=\"justify\">Voll Neugier und bed\u00e4chtigen Schrittes sollten wir die zahlreichen Pl\u00e4tze und Bergterrassen besuchen, wo die B\u00fcrgersteige sich im Schatten einer Wallfahrtskapelle oder eines Brunnens verbreitern. Wichtigster Punkt der Stadt ist die Plaza de Espa\u00f1a, begrenzt vom Rathaus und der Gemeinde El Salvador und bedeutendster architektonischer Renaissance-Bau des gesamten Archipels. Die abgetretenen Stufen f\u00fchren uns zum hoch gelegenen Stadtviertel San Sebasti\u00e1n, dem Kloster des Heiligen Dominikus und zur kleinen Wallfahrtskapelle von San Telmo.<\/p>\n<p align=\"justify\">Das pr\u00e4chtige Pflaster der Calle Real l\u00e4dt uns zur Plaza de Lo Divino, zum murmelnden Brunnen der Placeta Borrero und zur erfrischenden Alameda als H\u00f6hepunkt ein. Nicht Pappeln, sondern Lorbeerb\u00e4ume aus Spanisch-Amerika spenden der innigst geliebten Skulptur des &#8220;tanzenden Zwerges&#8221; Schatten. Von hier aus setzen wir unseren Weg fort zur Kirche des Heiligen Franziskus aus dem 16.Jahrhundert, in dessen Kloster sich das Inselmuseum befindet. An diesem Platz liegen die Schule f\u00fcr Musik und das Handwerkszentrum San Francisco.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Kirchen und Wallfahrtskapellen<\/strong><\/h4>\n<p><a href=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma4.jpg\" rel=\"attachment wp-att-1301\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1301 alignleft\" src=\"https:\/\/islabonita.com\/wp-content\/uploads\/2015\/08\/es_sc_palma_sc_palma4-195x300.jpg\" alt=\"es_sc_palma_sc_palma4\" width=\"195\" height=\"300\" \/><\/a><\/p>\n<p align=\"justify\">Vor 500 Jahren kamen Franziskaner- und Dominikanerm\u00f6nche auf die Insel und errichteten ihre Kl\u00f6ster, und im Laufe der Jahrhunderte vervielfachte sich die Anzahl an schlichten Wallfahrtskapellen. Diese kleinen einschiffigen Heiligt\u00fcmer mit dem Zauber der damaligen Zeit werden zu Ehren des Heiligen Josef, Heiligen Sebastian und Heiligen Telmo erhalten.<br \/>\nDie Kirchen wurden immer gr\u00f6\u00dfer und die verschiedenen Kunststile spiegelten sich in den Portalen und wundersch\u00f6nen Altarbildern wider. Die dicken wei\u00dfen Mauern und das Gest\u00fchl aus grauem Basalt sind ihnen allen als Kennzeichen der traditionellen kanarischen Architektur gemein. Die Gemeinden San Francisco, El Salvador, Santo Domingo, La Encarnaci\u00f3n, das Krankenhaus Nuestra Se\u00f1ora de Los Dolores, das Heiligtum Santuario de Las Nieves u.a. umfassen ein gro\u00dfes erstrangiges Verm\u00e4chtnis an Malerei und Bildhauerkunst im Stil der Gotik und Renaissance. Der Tausch von Zucker und Wein gegen fl\u00e4mische Kunstwerke vermehrt sich im 16.Jahrhundert; im 17.Jahrhundert verf\u00fcgen die K\u00fcnstler auf La Palma \u00fcber eine barocke Technik eigenen Stils und voller portugiesischer, fl\u00e4mischer, andalusischer, maurischer und amerikanischer Einfl\u00fcsse. Das die Schiffe und Kapellen unserer religi\u00f6sen Bauwerke bedeckende Dachwerk kann als vortrefflich und kompliziert bezeichnet werden. Die geometrischen Formen sind in pr\u00e4chtigen Balken aus Kienspan im Geist und Stil der maurischen Tradition geschnitzt.<\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n<h4 align=\"justify\"><span class=\"titular\"><strong>Das Schiff der Heiligen Jungfrau<\/strong><\/p>\n<p><\/span><\/h4>\n<p align=\"justify\">Die Masten der Santa Mar\u00eda ragen \u00fcber den B\u00e4umen der Alameda hervor. Als Nachbau der Karavelle von Kolumbus setzt sie alle f\u00fcnf Jahre bei der Feier der Bajada de La Virgen de Las Nieves ihre Segel und erlangt Leben im Dialog mit der auf der anderen Seite der Schlucht in Encarnaci\u00f3n liegenden Burg.<br \/>\nDie Bronzestatue des Zwergs erlebt vom Platz aus den nachgestellten Streit zwischen Schiff und Burg. Die Kanonen werden abgefeuert und erf\u00fcllen diesen Teil der Insel alle f\u00fcnf Jahre mit einem besonders festlichen Anhauch. Im Inneren des Schiffs ist das Schiffsmuseum untergebracht.<br \/>\n<span class=\"titular\"><br \/>\n<\/span><\/p>\n<h4 align=\"justify\"><span class=\"titular\"><strong>Das Heiligtum der &#8220;Jungfrau vom Schnee&#8221;<\/strong><\/p>\n<p><\/span><\/h4>\n<p align=\"justify\">Um zum au\u00dferhalb der Stadt gelegenen Heiligtum zu gelangen, schlagen wir die alte Planton-Stra\u00dfe ein. Wir sto\u00dfen auf die Burg Castillo de La Virgen und die erste Kirche der Gemeinde, die Encarnaci\u00f3n.<br \/>\nDas kostbarste Juwel im Marienraum ist das gotische mehrfarbige Terracotta-Bild, das laut \u00dcberlieferung seinen Namen dem Umstand zu verdanken hat, dass das Feuer eines Vulkans mit Schnee gel\u00f6scht wurde. Man sagt, dass die Ureinwohner bereits vor der Eroberung durch die Spanier zu der heutigen Inselpatronin beteten. Dieses Bild von knapp einem halben Meter Gr\u00f6\u00dfe aus dem 14.Jahrhundert wird von den Bewohnern der Insel ganz besonders verehrt. Alle f\u00fcnf Jahre wird es unter seinem Baldachin vom Heiligtum hinab in die Gemeinde El Salvador getragen.<br \/>\nIm Inneren des Heiligtums befindet sich ein religi\u00f6ses Museum.<br \/>\n<span class=\"titular\"><br \/>\n<\/span><\/p>\n<h4 align=\"justify\"><span class=\"titular\"><strong>Das Vergn\u00fcgungszentrum Fuente Ol\u00e9n<\/strong><\/p>\n<p><\/span><\/h4>\n<p align=\"justify\">Auf den Gipfeln der Gemeinde liegt das Vergn\u00fcgungszentrum Fuente Ol\u00e9n. Inmitten eines Pinienwaldes befindet sich diese Freizeitst\u00e4tte, die sich geradezu anbietet, um eine kleine Pause einzulegen und die Natur zu genie\u00dfen. Unter mehreren \u00fcberdachten Bauten stehen den Besuchern Tische, Grillpl\u00e4tze und Trinkwasser zur Verf\u00fcgung.<br \/>\nBei unserem Aufstieg weicht die Pinie dem Gei\u00dfklee, der sich zusammenzieht bei seinem Versuch, sich vor der K\u00e4lte des hohen Berges zu sch\u00fctzen. Auf 2.235 m H\u00f6he erreichen wir den h\u00f6chsten Punkt, den &#8220;Pico de la Nieve&#8221;, auf dem sich die sporadisch auftretenden winterlichen Schneef\u00e4lle ank\u00fcndigen.<br \/>\nDie Arch\u00e4ologie spielt die Hauptrolle an der Fundst\u00e4tte La Erita, wo wir uns der rituell-magischen Welt der von den Awaren gravierten Steine n\u00e4hern.<br \/>\n<span class=\"titular\"><br \/>\n<\/span><\/p>\n<h4 align=\"justify\"><span class=\"titular\"><strong>Der <strong>Naturschutzpark Las Nieves<\/strong>. <\/strong><\/p>\n<p><\/span><\/h4>\n<p align=\"justify\">Die Gebirgskunde der Insel \u00fcberrascht uns erneut in diesem Naturgebiet, wo der Mensch kaum Spuren hinterlassen hat. Die aufsehenerregende Formengestalt des Landes besch\u00fctzt einzelne \u00d6kosysteme der Fauna und Flora von hohem \u00f6kologischem Wert. Die Schluchten von Santa Cruz namens Quintero, El R\u00edo, La Madera und Dorador sind Teil des Naturschutzparks Las Nieves, der eine Fl\u00e4che von 5.090 ha umfasst.<br \/>\nDer Mensch wusste das Wasser zu nutzen, das diesem Garten zuflie\u00dft, und baute ein Netz von Kan\u00e4len, Br\u00fccken, ausgehobenen G\u00e4ngen, Wasserm\u00fchlen, El Electr\u00f3n (erstes Wasserkraftwerk der Kanarischen Inseln) usw. All dies zusammen bildet um das fl\u00fcssige Element herum eine Kultur, der das verbreitete Bild der Molinos de Bellido entnommen ist, die in diesem Naturgebiet liegen.<\/p>\n<p style=\"text-align: justify;\">Copyright. Asociaci\u00f3n para el Desarrollo Rural de la Isla de La Palma (ADER-La Palma).<\/p>\n","protected":false},"author":1,"featured_media":1298,"parent":0,"menu_order":0,"template":"","_links":{"self":[{"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/location\/140"}],"collection":[{"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/types\/location"}],"author":[{"embeddable":true,"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/media\/1298"}],"wp:attachment":[{"href":"https:\/\/islabonita.com\/de\/wp-json\/wp\/v2\/media?parent=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}